{"id":1993,"date":"2022-12-06T17:05:53","date_gmt":"2022-12-06T16:05:53","guid":{"rendered":"https:\/\/seksissach.ch\/v4\/?page_id=1993"},"modified":"2026-08-19T09:37:37","modified_gmt":"2026-08-19T07:37:37","slug":"lernraum-2","status":"publish","type":"page","link":"https:\/\/seksissach.ch\/v4\/lernraum-2\/","title":{"rendered":"Informationen zum Lernraum"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Der Lernraum bietet Sch\u00fclerinnen und Sch\u00fclern die M\u00f6glichkeit, in einem angenehmen Umfeld, Aufgaben zu erledigen. Ganz egal, ob es sich um Hausaufgaben, Gruppenarbeiten, Pr\u00fcfungsvorbereitungen oder verpassten Unterrichtsstoff handelt. Auch bei Bewerbungsschreiben helfen wir gerne. W\u00e4hrend der \u00d6ffnungszeiten sind Lehrpersonen unserer Schule als Lerncoaches vor Ort und unterst\u00fctzen bei Fragen und Problemen. Der Lernraum befindet sich im Lesezentrum, wo Computer, Drucker und Arbeitspl\u00e4tze zur Verf\u00fcgung stehen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Anmeldung ist nicht erforderlich, und die Sch\u00fclerinnen und Sch\u00fcler entscheiden selbst, wie lange und woran sie arbeiten m\u00f6chten. Das Angebot ist kostenlos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir freuen uns auf das gemeinsame Arbeiten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/seksissach.ch\/v4\/wp-content\/uploads\/2026\/08\/Lernraum2627-1024x575.png\" alt=\"\" class=\"wp-image-2602\" srcset=\"https:\/\/seksissach.ch\/v4\/wp-content\/uploads\/2026\/08\/Lernraum2627-1024x575.png 1024w, https:\/\/seksissach.ch\/v4\/wp-content\/uploads\/2026\/08\/Lernraum2627-300x169.png 300w, https:\/\/seksissach.ch\/v4\/wp-content\/uploads\/2026\/08\/Lernraum2627-768x431.png 768w, https:\/\/seksissach.ch\/v4\/wp-content\/uploads\/2026\/08\/Lernraum2627-1536x863.png 1536w, https:\/\/seksissach.ch\/v4\/wp-content\/uploads\/2026\/08\/Lernraum2627-2048x1150.png 2048w\" sizes=\"auto, (max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Lernraum bietet Sch\u00fclerinnen und Sch\u00fclern die M\u00f6glichkeit, in einem angenehmen Umfeld, Aufgaben zu erledigen. Ganz egal, ob es sich um Hausaufgaben, Gruppenarbeiten, Pr\u00fcfungsvorbereitungen oder verpassten Unterrichtsstoff handelt. Auch bei Bewerbungsschreiben helfen wir gerne. W\u00e4hrend der \u00d6ffnungszeiten sind Lehrpersonen unserer Schule als Lerncoaches vor Ort und unterst\u00fctzen bei Fragen und Problemen. Der Lernraum befindet sich &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/seksissach.ch\/v4\/lernraum-2\/\" class=\"more-link\"><span class=\"screen-reader-text\">\u201eInformationen zum Lernraum\u201c <\/span>weiterlesen<\/a><\/p>\n","protected":false},"author":2,"featured_media":361,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"pagelayer_contact_templates":[],"_pagelayer_content":"","footnotes":""},"class_list":["post-1993","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/seksissach.ch\/v4\/wp-json\/wp\/v2\/pages\/1993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/seksissach.ch\/v4\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/seksissach.ch\/v4\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/seksissach.ch\/v4\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/seksissach.ch\/v4\/wp-json\/wp\/v2\/comments?post=1993"}],"version-history":[{"count":7,"href":"https:\/\/seksissach.ch\/v4\/wp-json\/wp\/v2\/pages\/1993\/revisions"}],"predecessor-version":[{"id":2603,"href":"https:\/\/seksissach.ch\/v4\/wp-json\/wp\/v2\/pages\/1993\/revisions\/2603"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/seksissach.ch\/v4\/wp-json\/wp\/v2\/media\/361"}],"wp:attachment":[{"href":"https:\/\/seksissach.ch\/v4\/wp-json\/wp\/v2\/media?parent=1993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}